{"id":88000,"date":"2017-11-24T15:50:22","date_gmt":"2017-11-24T13:50:22","guid":{"rendered":"http:\/\/www.anteprima24.it\/?p=88000"},"modified":"2017-11-27T15:17:26","modified_gmt":"2017-11-27T13:17:26","slug":"telecamere-villa-sicurezza-inaugurazione","status":"publish","type":"post","link":"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/","title":{"rendered":"Oggi le telecamere, domani l&#8217;illuminazione: &#8220;Faremo della villa un vanto&#8221; (VIDEO)"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Tempo di lettura: <\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">minuti<\/span><\/span><p>\u201cFaremo di questa villa un ulteriore motivo di vanto per la citt\u00e0\u201d. Inaugurato questa mattina il sistema di videosorveglianza della Villa Comunale del capoluogo.<\/p>\n<p>Soltanto uno degli step utili a valorizzare i giardini inaugurati nel 1879 dall\u2019allora sindaco Manciotti. Da una fascia tricolore all\u2019altra, ora \u00e8 <strong>Clemente Mastella<\/strong> a voler dare nuovo slancio a uno dei luoghi simbolo di Benevento. \u201cCon la videosorveglianza interveniamo sul tema della sicurezza. Tutti sono liberi di vivere questi spazi ma con rispetto e seriet\u00e0. Altrimenti \u00e8 doveroso l\u2019intervento della pubblica autorit\u00e0\u201d.<\/p>\n<p>A facilitare il compito dalle forze dell\u2019ordine, rappresentate oggi dal questore Giuseppe Bellassai e dal comandante della polizia municipale Giovanni Fantasia, dodici telecamere dislocate lungo il perimetro della Villa Comunale. \u201cMonitoreremo \u2013 spiega <strong>Fantasia<\/strong> \u2013 gli accessi e i luoghi pi\u00f9 nascosti. Tutti i dati saranno conservati secondo le disposizioni della legge. Ma le telecamere ci consentiranno anche di prevenire comportamenti scorretti, attraverso meccanismi di preallarme che scatteranno grazie ai rilievi automatici dei volti\u201d.<\/p>\n<p>Non solo sicurezza, dicevamo. Nella prossima primavera \u00e8 prevista l\u2019installazione, con l\u2019intervento della Conad che ha adottato alcuni spazi della villa, di nuove giostre per bambini. Sempre attraverso l\u2019attivismo di alcuni imprenditori, poi, la villa \u2013 annuncia Mastella \u2013 \u201csar\u00e0 oggetto di una forma speciale di illuminazione\u201d. Una operazione che riguarder\u00e0 anche gli esterni del Duomo di Benevento e pi\u00f9 in l\u00e0 la statua del Bue Apis.<\/p>\n<p>\u201cIl sistema di videosorveglianza che inauguriamo oggi ci consentir\u00e0 anche un grande risparmio di risorse umane \u2013 ha dichiarato il questore <strong>Bellassai<\/strong>. Allo stesso tempo, per\u00f2, garantiremo alle famiglie un grado di sicurezza elevato\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-88005\" src=\"http:\/\/www.anteprima24.it\/wp-content\/uploads\/2017\/11\/Villa2-650x366.jpg\" alt=\"\" width=\"650\" height=\"366\" srcset=\"https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa2-650x366.jpg 650w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa2-250x141.jpg 250w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa2-400x225.jpg 400w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa2-768x432.jpg 768w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa2-30x17.jpg 30w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa2-150x84.jpg 150w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa2-50x28.jpg 50w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa2-100x56.jpg 100w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa2-200x113.jpg 200w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa2-300x169.jpg 300w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa2-350x197.jpg 350w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa2-450x253.jpg 450w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa2-500x281.jpg 500w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa2-550x309.jpg 550w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa2-800x450.jpg 800w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa2-1200x675.jpg 1200w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa2-1600x900.jpg 1600w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa2-2000x1125.jpg 2000w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa2.jpg 2048w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-88006\" src=\"http:\/\/www.anteprima24.it\/wp-content\/uploads\/2017\/11\/Villa3-650x366.jpg\" alt=\"\" width=\"650\" height=\"366\" srcset=\"https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa3-650x366.jpg 650w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa3-250x141.jpg 250w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa3-400x225.jpg 400w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa3-768x432.jpg 768w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa3-30x17.jpg 30w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa3-150x84.jpg 150w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa3-50x28.jpg 50w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa3-100x56.jpg 100w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa3-200x113.jpg 200w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa3-300x169.jpg 300w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa3-350x197.jpg 350w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa3-450x253.jpg 450w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa3-500x281.jpg 500w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa3-550x309.jpg 550w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa3-800x450.jpg 800w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa3-1200x675.jpg 1200w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa3-1600x900.jpg 1600w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa3-2000x1125.jpg 2000w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa3.jpg 2048w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-88008\" src=\"http:\/\/www.anteprima24.it\/wp-content\/uploads\/2017\/11\/Villa4-650x366.jpg\" alt=\"\" width=\"650\" height=\"366\" srcset=\"https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa4-650x366.jpg 650w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa4-250x141.jpg 250w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa4-400x225.jpg 400w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa4-768x432.jpg 768w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa4-30x17.jpg 30w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa4-150x84.jpg 150w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa4-50x28.jpg 50w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa4-100x56.jpg 100w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa4-200x113.jpg 200w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa4-300x169.jpg 300w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa4-350x197.jpg 350w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa4-450x253.jpg 450w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa4-500x281.jpg 500w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa4-550x309.jpg 550w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa4-800x450.jpg 800w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa4-1200x675.jpg 1200w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa4-1600x900.jpg 1600w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa4-2000x1125.jpg 2000w, https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa4.jpg 2048w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cFaremo di questa villa un ulteriore motivo di vanto per la citt\u00e0\u201d. Inaugurato questa mattina il sistema di videosorveglianza della Villa Comunale del capoluogo. Soltanto uno degli step utili a valorizzare i giardini inaugurati nel 1879 dall\u2019allora sindaco Manciotti. Da una fascia tricolore all\u2019altra, ora \u00e8 Clemente Mastella a voler dare nuovo slancio a uno [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":88004,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[1374,390,15391,2,789,271],"tags":[40,15062,360,3794],"class_list":{"0":"post-88000","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-attualita-benevento","8":"category-attualita-regione","9":"category-video-benevento","10":"category-benevento","11":"category-primo-piano-benevento","12":"category-regione","13":"tag-benevento","14":"tag-clemente-mastella-sindaco","15":"tag-sicurezza","16":"tag-villa-comunale"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oggi le telecamere, domani l&#039;illuminazione: &quot;Faremo della villa un vanto&quot; (VIDEO)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oggi le telecamere, domani l&#039;illuminazione: &quot;Faremo della villa un vanto&quot; (VIDEO)\" \/>\n<meta property=\"og:description\" content=\"\u201cFaremo di questa villa un ulteriore motivo di vanto per la citt\u00e0\u201d. Inaugurato questa mattina il sistema di videosorveglianza della Villa Comunale del capoluogo. Soltanto uno degli step utili a valorizzare i giardini inaugurati nel 1879 dall\u2019allora sindaco Manciotti. Da una fascia tricolore all\u2019altra, ora \u00e8 Clemente Mastella a voler dare nuovo slancio a uno [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Anteprima24.it\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-24T13:50:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-27T13:17:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Antonio Corbo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Corbo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/\"},\"author\":{\"name\":\"Antonio Corbo\",\"@id\":\"https:\/\/www.anteprima24.it\/archivio\/#\/schema\/person\/07e04b73b7c116c79ec12cf3dc8ef618\"},\"headline\":\"Oggi le telecamere, domani l&#8217;illuminazione: &#8220;Faremo della villa un vanto&#8221; (VIDEO)\",\"datePublished\":\"2017-11-24T13:50:22+00:00\",\"dateModified\":\"2017-11-27T13:17:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/\"},\"wordCount\":272,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa1.jpg\",\"keywords\":[\"Benevento\",\"Clemente Mastella Sindaco\",\"sicurezza\",\"villa comunale\"],\"articleSection\":[\"Attualit\u00e0 Benevento\",\"Attualit\u00e0 Regione\",\"Benevento\",\"Benevento\",\"Primo Piano Benevento\",\"Regione\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/\",\"url\":\"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/\",\"name\":\"Oggi le telecamere, domani l'illuminazione: \\\"Faremo della villa un vanto\\\" (VIDEO)\",\"isPartOf\":{\"@id\":\"https:\/\/www.anteprima24.it\/archivio\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa1.jpg\",\"datePublished\":\"2017-11-24T13:50:22+00:00\",\"dateModified\":\"2017-11-27T13:17:26+00:00\",\"author\":{\"@id\":\"https:\/\/www.anteprima24.it\/archivio\/#\/schema\/person\/07e04b73b7c116c79ec12cf3dc8ef618\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/#primaryimage\",\"url\":\"https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa1.jpg\",\"contentUrl\":\"https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa1.jpg\",\"width\":2048,\"height\":1152},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.anteprima24.it\/archivio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oggi le telecamere, domani l&#8217;illuminazione: &#8220;Faremo della villa un vanto&#8221; (VIDEO)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.anteprima24.it\/archivio\/#website\",\"url\":\"https:\/\/www.anteprima24.it\/archivio\/\",\"name\":\"Anteprima24.it\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.anteprima24.it\/archivio\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.anteprima24.it\/archivio\/#\/schema\/person\/07e04b73b7c116c79ec12cf3dc8ef618\",\"name\":\"Antonio Corbo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.anteprima24.it\/archivio\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5037141d2b5caa3eee42644f6a67c08a1d5339b9c46f9531ac907505d2c8efed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5037141d2b5caa3eee42644f6a67c08a1d5339b9c46f9531ac907505d2c8efed?s=96&d=mm&r=g\",\"caption\":\"Antonio Corbo\"},\"url\":\"https:\/\/www.anteprima24.it\/archivio\/author\/antoniocorbo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oggi le telecamere, domani l'illuminazione: \"Faremo della villa un vanto\" (VIDEO)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/","og_locale":"it_IT","og_type":"article","og_title":"Oggi le telecamere, domani l'illuminazione: \"Faremo della villa un vanto\" (VIDEO)","og_description":"\u201cFaremo di questa villa un ulteriore motivo di vanto per la citt\u00e0\u201d. Inaugurato questa mattina il sistema di videosorveglianza della Villa Comunale del capoluogo. Soltanto uno degli step utili a valorizzare i giardini inaugurati nel 1879 dall\u2019allora sindaco Manciotti. Da una fascia tricolore all\u2019altra, ora \u00e8 Clemente Mastella a voler dare nuovo slancio a uno [&hellip;]","og_url":"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/","og_site_name":"Anteprima24.it","article_published_time":"2017-11-24T13:50:22+00:00","article_modified_time":"2017-11-27T13:17:26+00:00","og_image":[{"width":2048,"height":1152,"url":"https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa1.jpg","type":"image\/jpeg"}],"author":"Antonio Corbo","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Antonio Corbo","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/#article","isPartOf":{"@id":"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/"},"author":{"name":"Antonio Corbo","@id":"https:\/\/www.anteprima24.it\/archivio\/#\/schema\/person\/07e04b73b7c116c79ec12cf3dc8ef618"},"headline":"Oggi le telecamere, domani l&#8217;illuminazione: &#8220;Faremo della villa un vanto&#8221; (VIDEO)","datePublished":"2017-11-24T13:50:22+00:00","dateModified":"2017-11-27T13:17:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/"},"wordCount":272,"commentCount":0,"image":{"@id":"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa1.jpg","keywords":["Benevento","Clemente Mastella Sindaco","sicurezza","villa comunale"],"articleSection":["Attualit\u00e0 Benevento","Attualit\u00e0 Regione","Benevento","Benevento","Primo Piano Benevento","Regione"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/","url":"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/","name":"Oggi le telecamere, domani l'illuminazione: \"Faremo della villa un vanto\" (VIDEO)","isPartOf":{"@id":"https:\/\/www.anteprima24.it\/archivio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/#primaryimage"},"image":{"@id":"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa1.jpg","datePublished":"2017-11-24T13:50:22+00:00","dateModified":"2017-11-27T13:17:26+00:00","author":{"@id":"https:\/\/www.anteprima24.it\/archivio\/#\/schema\/person\/07e04b73b7c116c79ec12cf3dc8ef618"},"breadcrumb":{"@id":"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/#primaryimage","url":"https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa1.jpg","contentUrl":"https:\/\/www.anteprima24.it\/archivio\/wp-content\/uploads\/2017\/11\/Villa1.jpg","width":2048,"height":1152},{"@type":"BreadcrumbList","@id":"https:\/\/www.anteprima24.it\/archivio\/benevento\/telecamere-villa-sicurezza-inaugurazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.anteprima24.it\/archivio\/"},{"@type":"ListItem","position":2,"name":"Oggi le telecamere, domani l&#8217;illuminazione: &#8220;Faremo della villa un vanto&#8221; (VIDEO)"}]},{"@type":"WebSite","@id":"https:\/\/www.anteprima24.it\/archivio\/#website","url":"https:\/\/www.anteprima24.it\/archivio\/","name":"Anteprima24.it","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.anteprima24.it\/archivio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.anteprima24.it\/archivio\/#\/schema\/person\/07e04b73b7c116c79ec12cf3dc8ef618","name":"Antonio Corbo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.anteprima24.it\/archivio\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5037141d2b5caa3eee42644f6a67c08a1d5339b9c46f9531ac907505d2c8efed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5037141d2b5caa3eee42644f6a67c08a1d5339b9c46f9531ac907505d2c8efed?s=96&d=mm&r=g","caption":"Antonio Corbo"},"url":"https:\/\/www.anteprima24.it\/archivio\/author\/antoniocorbo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.anteprima24.it\/archivio\/wp-json\/wp\/v2\/posts\/88000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.anteprima24.it\/archivio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.anteprima24.it\/archivio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.anteprima24.it\/archivio\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.anteprima24.it\/archivio\/wp-json\/wp\/v2\/comments?post=88000"}],"version-history":[{"count":0,"href":"https:\/\/www.anteprima24.it\/archivio\/wp-json\/wp\/v2\/posts\/88000\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.anteprima24.it\/archivio\/wp-json\/wp\/v2\/media\/88004"}],"wp:attachment":[{"href":"https:\/\/www.anteprima24.it\/archivio\/wp-json\/wp\/v2\/media?parent=88000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.anteprima24.it\/archivio\/wp-json\/wp\/v2\/categories?post=88000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.anteprima24.it\/archivio\/wp-json\/wp\/v2\/tags?post=88000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}